{"id":3942,"count":1,"description":"","link":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/","name":"G\u00f6\u00e7men D\u00fczenlemesi","slug":"gocmen-duzenlemesi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G\u00f6\u00e7men D\u00fczenlemesi ar\u015fivleri - Kuzeyin Sesi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00f6\u00e7men D\u00fczenlemesi ar\u015fivleri - Kuzeyin Sesi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/\" \/>\n<meta property=\"og:site_name\" content=\"Kuzeyin Sesi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kuzeyinsesii\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/tag\\\/gocmen-duzenlemesi\\\/\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/tag\\\/gocmen-duzenlemesi\\\/\",\"name\":\"G\u00f6\u00e7men D\u00fczenlemesi ar\u015fivleri - Kuzeyin Sesi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/tag\\\/gocmen-duzenlemesi\\\/#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/tag\\\/gocmen-duzenlemesi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/kuzeyinsesi.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G\u00f6\u00e7men D\u00fczenlemesi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#website\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/\",\"name\":\"Kuzeyin Sesi\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kuzeyinsesi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G\u00f6\u00e7men D\u00fczenlemesi ar\u015fivleri - Kuzeyin Sesi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/","og_locale":"tr_TR","og_type":"article","og_title":"G\u00f6\u00e7men D\u00fczenlemesi ar\u015fivleri - Kuzeyin Sesi","og_url":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/","og_site_name":"Kuzeyin Sesi","twitter_card":"summary_large_image","twitter_site":"@kuzeyinsesii","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/","url":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/","name":"G\u00f6\u00e7men D\u00fczenlemesi ar\u015fivleri - Kuzeyin Sesi","isPartOf":{"@id":"https:\/\/kuzeyinsesi.org\/#website"},"breadcrumb":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/kuzeyinsesi.org\/index.php\/tag\/gocmen-duzenlemesi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/kuzeyinsesi.org\/"},{"@type":"ListItem","position":2,"name":"G\u00f6\u00e7men D\u00fczenlemesi"}]},{"@type":"WebSite","@id":"https:\/\/kuzeyinsesi.org\/#website","url":"https:\/\/kuzeyinsesi.org\/","name":"Kuzeyin Sesi","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kuzeyinsesi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"}]}},"_links":{"self":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/tags\/3942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts?tags=3942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}