{"id":36221,"date":"2026-03-06T12:12:15","date_gmt":"2026-03-06T10:12:15","guid":{"rendered":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/"},"modified":"2026-03-06T12:12:15","modified_gmt":"2026-03-06T10:12:15","slug":"super-ligde-yeni-sezon-14-agustosta-baslayacak","status":"publish","type":"post","link":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/","title":{"rendered":"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak"},"content":{"rendered":"<p><\/p>\n<div>\n<p>&#13;<br \/>\n\tT\u00fcrkiye Futbol Federasyonundan yap\u0131lan a\u00e7\u0131klamaya g\u00f6re Trendyol S\u00fcper Lig, 14-17 A\u011fustos; Trendyol 1. Lig ise 7-10 A\u011fustos tarihlerinde oynanacak ma\u00e7larla ba\u015flayacak.<\/p>\n<p>&#13;<br \/>\n\tNesine 2. Lig ve Nesine 3. Lig&#8217;de ise ilk m\u00fcsabakalar, 5-6 Eyl\u00fcl&#8217;de oynanacak.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#13; T\u00fcrkiye Futbol Federasyonundan yap\u0131lan a\u00e7\u0131klamaya g\u00f6re Trendyol S\u00fcper Lig, 14-17 A\u011fustos; Trendyol 1. Lig ise 7-10 A\u011fustos tarihlerinde oynanacak ma\u00e7larla ba\u015flayacak. &#13; Nesine 2. Lig ve Nesine 3. Lig&#8217;de ise ilk m\u00fcsabakalar, 5-6 Eyl\u00fcl&#8217;de oynanacak.<\/p>\n","protected":false},"author":1,"featured_media":30051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-36221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak - Kuzeyin Sesi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak - Kuzeyin Sesi\" \/>\n<meta property=\"og:description\" content=\"&#013; T\u00fcrkiye Futbol Federasyonundan yap\u0131lan a\u00e7\u0131klamaya g\u00f6re Trendyol S\u00fcper Lig, 14-17 A\u011fustos; Trendyol 1. Lig ise 7-10 A\u011fustos tarihlerinde oynanacak ma\u00e7larla ba\u015flayacak. &#013; Nesine 2. Lig ve Nesine 3. Lig&#8217;de ise ilk m\u00fcsabakalar, 5-6 Eyl\u00fcl&#8217;de oynanacak.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/\" \/>\n<meta property=\"og:site_name\" content=\"Kuzeyin Sesi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuzeyinsesii\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T10:12:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trthaberstatic.cdn.wp.trt.com.tr\/resimler\/2386000\/super-lig-2386888.jpg\" \/>\n<meta name=\"author\" content=\"Kuzeyin Sesi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kuzeyinsesii\" \/>\n<meta name=\"twitter:site\" content=\"@kuzeyinsesii\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kuzeyin Sesi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/\"},\"author\":{\"name\":\"Kuzeyin Sesi\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#\\\/schema\\\/person\\\/9f859689cdf01485597712386e37f5aa\"},\"headline\":\"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak\",\"datePublished\":\"2026-03-06T10:12:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/\"},\"wordCount\":55,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/super-lig-2386888.jpg\",\"articleSection\":[\"Spor\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/\",\"name\":\"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak - Kuzeyin Sesi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/super-lig-2386888.jpg\",\"datePublished\":\"2026-03-06T10:12:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#\\\/schema\\\/person\\\/9f859689cdf01485597712386e37f5aa\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/super-lig-2386888.jpg\",\"contentUrl\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/super-lig-2386888.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2026\\\/03\\\/06\\\/super-ligde-yeni-sezon-14-agustosta-baslayacak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/kuzeyinsesi.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#website\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/\",\"name\":\"Kuzeyin Sesi\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kuzeyinsesi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#\\\/schema\\\/person\\\/9f859689cdf01485597712386e37f5aa\",\"name\":\"Kuzeyin Sesi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g\",\"caption\":\"Kuzeyin Sesi\"},\"sameAs\":[\"https:\\\/\\\/kuzeyinsesi.org\"],\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/author\\\/guven\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak - Kuzeyin Sesi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/","og_locale":"tr_TR","og_type":"article","og_title":"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak - Kuzeyin Sesi","og_description":"&#13; T\u00fcrkiye Futbol Federasyonundan yap\u0131lan a\u00e7\u0131klamaya g\u00f6re Trendyol S\u00fcper Lig, 14-17 A\u011fustos; Trendyol 1. Lig ise 7-10 A\u011fustos tarihlerinde oynanacak ma\u00e7larla ba\u015flayacak. &#13; Nesine 2. Lig ve Nesine 3. Lig&#8217;de ise ilk m\u00fcsabakalar, 5-6 Eyl\u00fcl&#8217;de oynanacak.","og_url":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/","og_site_name":"Kuzeyin Sesi","article_publisher":"https:\/\/www.facebook.com\/kuzeyinsesii","article_published_time":"2026-03-06T10:12:15+00:00","og_image":[{"url":"https:\/\/trthaberstatic.cdn.wp.trt.com.tr\/resimler\/2386000\/super-lig-2386888.jpg","type":"","width":"","height":""}],"author":"Kuzeyin Sesi","twitter_card":"summary_large_image","twitter_creator":"@kuzeyinsesii","twitter_site":"@kuzeyinsesii","twitter_misc":{"Yazan:":"Kuzeyin Sesi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#article","isPartOf":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/"},"author":{"name":"Kuzeyin Sesi","@id":"https:\/\/kuzeyinsesi.org\/#\/schema\/person\/9f859689cdf01485597712386e37f5aa"},"headline":"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak","datePublished":"2026-03-06T10:12:15+00:00","mainEntityOfPage":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/"},"wordCount":55,"commentCount":0,"image":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#primaryimage"},"thumbnailUrl":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2025\/08\/super-lig-2386888.jpg","articleSection":["Spor"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/","url":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/","name":"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak - Kuzeyin Sesi","isPartOf":{"@id":"https:\/\/kuzeyinsesi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#primaryimage"},"image":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#primaryimage"},"thumbnailUrl":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2025\/08\/super-lig-2386888.jpg","datePublished":"2026-03-06T10:12:15+00:00","author":{"@id":"https:\/\/kuzeyinsesi.org\/#\/schema\/person\/9f859689cdf01485597712386e37f5aa"},"breadcrumb":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#primaryimage","url":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2025\/08\/super-lig-2386888.jpg","contentUrl":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2025\/08\/super-lig-2386888.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2026\/03\/06\/super-ligde-yeni-sezon-14-agustosta-baslayacak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/kuzeyinsesi.org\/"},{"@type":"ListItem","position":2,"name":"S\u00fcper Lig&#039;de yeni sezon 14 A\u011fustos&#039;ta ba\u015flayacak"}]},{"@type":"WebSite","@id":"https:\/\/kuzeyinsesi.org\/#website","url":"https:\/\/kuzeyinsesi.org\/","name":"Kuzeyin Sesi","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kuzeyinsesi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/kuzeyinsesi.org\/#\/schema\/person\/9f859689cdf01485597712386e37f5aa","name":"Kuzeyin Sesi","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/secure.gravatar.com\/avatar\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g","caption":"Kuzeyin Sesi"},"sameAs":["https:\/\/kuzeyinsesi.org"],"url":"https:\/\/kuzeyinsesi.org\/index.php\/author\/guven\/"}]}},"_links":{"self":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts\/36221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/comments?post=36221"}],"version-history":[{"count":0,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts\/36221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/media\/30051"}],"wp:attachment":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/media?parent=36221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/categories?post=36221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/tags?post=36221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}