{"id":260,"date":"2024-04-24T15:54:23","date_gmt":"2024-04-24T12:54:23","guid":{"rendered":"https:\/\/kuzeyinsesi.com\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/"},"modified":"2024-04-24T15:54:23","modified_gmt":"2024-04-24T12:54:23","slug":"gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi","status":"publish","type":"post","link":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/","title":{"rendered":"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131"},"content":{"rendered":"<div>\n<div class=\"mariselle-image-container center\">\n                                            <\/div>\n<p>Gelir ve Vergi Dairesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc, 30 Nisan 2024 tarihine kadar sunulmas\u0131 zorunlu olan 2023 y\u0131l\u0131 gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresinin uzat\u0131ld\u0131\u011f\u0131n\u0131 duyurdu .<\/p>\n<p>Buna g\u00f6re, son beyan tarihi kurumlar vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in 30 May\u0131s 2024, gelir vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in ise 24 Haziran 2024 mesai bitimi olarak a\u00e7\u0131kland\u0131.<\/p>\n<\/p><\/div>\n<p><script async\n                    defer\n                    crossorigin=\"anonymous\"\n                    src=\"https:\/\/connect.facebook.net\/tr_TR\/sdk.js#xfbml=1&#038;version=v3.3\"\n            ><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gelir ve Vergi Dairesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc, 30 Nisan 2024 tarihine kadar sunulmas\u0131 zorunlu olan 2023 y\u0131l\u0131 gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresinin uzat\u0131ld\u0131\u011f\u0131n\u0131 duyurdu . Buna g\u00f6re, son beyan tarihi kurumlar vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in 30 May\u0131s 2024, gelir vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in ise 24 Haziran 2024 mesai bitimi olarak a\u00e7\u0131kland\u0131.<\/p>\n","protected":false},"author":1,"featured_media":261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kibris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131 - Kuzeyin Sesi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131 - Kuzeyin Sesi\" \/>\n<meta property=\"og:description\" content=\"Gelir ve Vergi Dairesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc, 30 Nisan 2024 tarihine kadar sunulmas\u0131 zorunlu olan 2023 y\u0131l\u0131 gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresinin uzat\u0131ld\u0131\u011f\u0131n\u0131 duyurdu . Buna g\u00f6re, son beyan tarihi kurumlar vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in 30 May\u0131s 2024, gelir vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in ise 24 Haziran 2024 mesai bitimi olarak a\u00e7\u0131kland\u0131.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/\" \/>\n<meta property=\"og:site_name\" content=\"Kuzeyin Sesi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kuzeyinsesii\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T12:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2024\/04\/maliye-bakanligi3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kuzeyin Sesi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kuzeyinsesii\" \/>\n<meta name=\"twitter:site\" content=\"@kuzeyinsesii\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kuzeyin Sesi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/\"},\"author\":{\"name\":\"Kuzeyin Sesi\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#\\\/schema\\\/person\\\/9f859689cdf01485597712386e37f5aa\"},\"headline\":\"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131\",\"datePublished\":\"2024-04-24T12:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/\"},\"wordCount\":76,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/maliye-bakanligi3.jpeg\",\"articleSection\":[\"K\u0131br\u0131s\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/\",\"name\":\"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131 - Kuzeyin Sesi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/maliye-bakanligi3.jpeg\",\"datePublished\":\"2024-04-24T12:54:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#\\\/schema\\\/person\\\/9f859689cdf01485597712386e37f5aa\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/maliye-bakanligi3.jpeg\",\"contentUrl\":\"https:\\\/\\\/kuzeyinsesi.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/maliye-bakanligi3.jpeg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/2024\\\/04\\\/24\\\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/kuzeyinsesi.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#website\",\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/\",\"name\":\"Kuzeyin Sesi\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kuzeyinsesi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kuzeyinsesi.org\\\/#\\\/schema\\\/person\\\/9f859689cdf01485597712386e37f5aa\",\"name\":\"Kuzeyin Sesi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g\",\"caption\":\"Kuzeyin Sesi\"},\"sameAs\":[\"https:\\\/\\\/kuzeyinsesi.org\"],\"url\":\"https:\\\/\\\/kuzeyinsesi.org\\\/index.php\\\/author\\\/guven\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131 - Kuzeyin Sesi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/","og_locale":"tr_TR","og_type":"article","og_title":"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131 - Kuzeyin Sesi","og_description":"Gelir ve Vergi Dairesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc, 30 Nisan 2024 tarihine kadar sunulmas\u0131 zorunlu olan 2023 y\u0131l\u0131 gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresinin uzat\u0131ld\u0131\u011f\u0131n\u0131 duyurdu . Buna g\u00f6re, son beyan tarihi kurumlar vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in 30 May\u0131s 2024, gelir vergisi y\u00fck\u00fcml\u00fcleri i\u00e7in ise 24 Haziran 2024 mesai bitimi olarak a\u00e7\u0131kland\u0131.","og_url":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/","og_site_name":"Kuzeyin Sesi","article_publisher":"https:\/\/www.facebook.com\/kuzeyinsesii","article_published_time":"2024-04-24T12:54:23+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2024\/04\/maliye-bakanligi3.jpeg","type":"image\/jpeg"}],"author":"Kuzeyin Sesi","twitter_card":"summary_large_image","twitter_creator":"@kuzeyinsesii","twitter_site":"@kuzeyinsesii","twitter_misc":{"Yazan:":"Kuzeyin Sesi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#article","isPartOf":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/"},"author":{"name":"Kuzeyin Sesi","@id":"https:\/\/kuzeyinsesi.org\/#\/schema\/person\/9f859689cdf01485597712386e37f5aa"},"headline":"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131","datePublished":"2024-04-24T12:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/"},"wordCount":76,"commentCount":0,"image":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#primaryimage"},"thumbnailUrl":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2024\/04\/maliye-bakanligi3.jpeg","articleSection":["K\u0131br\u0131s"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/","url":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/","name":"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131 - Kuzeyin Sesi","isPartOf":{"@id":"https:\/\/kuzeyinsesi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#primaryimage"},"image":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#primaryimage"},"thumbnailUrl":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2024\/04\/maliye-bakanligi3.jpeg","datePublished":"2024-04-24T12:54:23+00:00","author":{"@id":"https:\/\/kuzeyinsesi.org\/#\/schema\/person\/9f859689cdf01485597712386e37f5aa"},"breadcrumb":{"@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#primaryimage","url":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2024\/04\/maliye-bakanligi3.jpeg","contentUrl":"https:\/\/kuzeyinsesi.org\/wp-content\/uploads\/2024\/04\/maliye-bakanligi3.jpeg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/kuzeyinsesi.org\/index.php\/2024\/04\/24\/gelir-vergisi-ve-kurumlar-vergisi-beyannameleri-icin-beyan-verme-suresi-uzatildi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/kuzeyinsesi.org\/"},{"@type":"ListItem","position":2,"name":"Gelir vergisi ve kurumlar vergisi beyannameleri i\u00e7in beyan verme s\u00fcresi uzat\u0131ld\u0131"}]},{"@type":"WebSite","@id":"https:\/\/kuzeyinsesi.org\/#website","url":"https:\/\/kuzeyinsesi.org\/","name":"Kuzeyin Sesi","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kuzeyinsesi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/kuzeyinsesi.org\/#\/schema\/person\/9f859689cdf01485597712386e37f5aa","name":"Kuzeyin Sesi","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/secure.gravatar.com\/avatar\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bab33852abfd8b282518d6ed81826833d77c3c882d9ab608add591ccace47a44?s=96&d=mm&r=g","caption":"Kuzeyin Sesi"},"sameAs":["https:\/\/kuzeyinsesi.org"],"url":"https:\/\/kuzeyinsesi.org\/index.php\/author\/guven\/"}]}},"_links":{"self":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":0,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/posts\/260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/media\/261"}],"wp:attachment":[{"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/media?parent=260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/categories?post=260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kuzeyinsesi.org\/index.php\/wp-json\/wp\/v2\/tags?post=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}